{"id":465,"date":"2016-09-27T14:57:56","date_gmt":"2016-09-27T14:57:56","guid":{"rendered":"http:\/\/fitness2.mythemecloud.io\/?page_id=465"},"modified":"2025-08-11T10:21:01","modified_gmt":"2025-08-11T08:21:01","slug":"ueberuns","status":"publish","type":"page","link":"https:\/\/august-kayser-stiftung.de\/index.php\/ueberuns\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"465\" class=\"elementor elementor-465\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0af31c4 e-flex e-con-boxed e-con e-parent\" data-id=\"0af31c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/august-kayser-stiftung.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/DJI_20240806180123_0042_D_4.mp4&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0246290 e-flex e-con-boxed e-con e-parent\" data-id=\"0246290\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-24d8dd8 e-con-full e-flex e-con e-child\" data-id=\"24d8dd8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38a6424 elementor-widget elementor-widget-heading\" data-id=\"38a6424\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ansprechpartner<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31f845e elementor-widget elementor-widget-text-editor\" data-id=\"31f845e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"pclass\">Heimleitung: Brigitte Klitta<\/div><div class=\"pclass\"><br \/><br \/>Dimitri Eberle<\/div><div class=\"pclass\">(Pflegedienstleiter)<\/div><div class=\"pclass\"><br \/><br \/>Tel. 07231\/96 60 50<\/div><div class=\"pclass\">Fax 07231\/96 60 14<\/div><div class=\"pclass\">\u00a0<\/div><div class=\"pclass\">E-Mail:\u00a0<a href=\"mailto:dimitri.eberle@august-kayser-stiftung.de\">dimitri.eberle@august-kayser-stiftung.de<\/a><\/div><div class=\"pclass\">\u00a0<\/div><div class=\"pclass\"><br \/>Elisabeth Komorek<\/div><div class=\"pclass\">(Leiterin des Sozialdienstes)<br \/><br \/>Tel. 07231\/96 60 10<\/div><div class=\"pclass\">Fax 07231\/96 60 14<\/div><div class=\"pclass\">\u00a0<\/div><div class=\"pclass\">E-Mail:\u00a0<a href=\"mailto:elisabeth.komorek@august-kayser-stiftung.de\">elisabeth.komorek@august-kayser-stiftung.de<\/a><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dedfcd e-con-full e-flex e-con e-child\" data-id=\"4dedfcd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14a68fa elementor-widget elementor-widget-image\" data-id=\"14a68fa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050193-1024x683.jpg\" class=\"attachment-large size-large wp-image-1463\" alt=\"Bild der Leiterin, Frau Klitta\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050193-1024x683.jpg 1024w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050193-300x200.jpg 300w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050193-768x512.jpg 768w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050193.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5c145e e-con-full e-flex e-con e-child\" data-id=\"e5c145e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b61769f elementor-widget elementor-widget-heading\" data-id=\"b61769f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Unsere Sponsoren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1519552 elementor-widget elementor-widget-text-editor\" data-id=\"1519552\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die August Kayser Stiftung bedankt sich recht herzlich f\u00fcr die Unterst\u00fctzung!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7a209d e-flex e-con-boxed e-con e-parent\" data-id=\"e7a209d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5835202 e-con-full e-flex e-con e-child\" data-id=\"5835202\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b42a0a5 elementor-widget elementor-widget-image\" data-id=\"b42a0a5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/wollmer.png\" class=\"attachment-large size-large wp-image-1649\" alt=\"Logo Wollmer\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/wollmer.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/wollmer-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c0b388f e-con-full e-flex e-con e-child\" data-id=\"c0b388f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8ef3d3 elementor-widget elementor-widget-image\" data-id=\"e8ef3d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/woertz.png\" class=\"attachment-large size-large wp-image-1650\" alt=\"Logo Planungsb\u00fcro W\u00f6rtz\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/woertz.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/woertz-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8713bc3 e-con-full e-flex e-con e-child\" data-id=\"8713bc3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f657f95 elementor-widget elementor-widget-image\" data-id=\"f657f95\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/staib.png\" class=\"attachment-large size-large wp-image-1648\" alt=\"Logo Elektro Staib\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/staib.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/staib-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f694ad e-con-full e-flex e-con e-child\" data-id=\"2f694ad\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60caa0f elementor-widget elementor-widget-image\" data-id=\"60caa0f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/schneider.png\" class=\"attachment-large size-large wp-image-1647\" alt=\"Logo Physiotherapie Schneider\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/schneider.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/schneider-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f52561 e-con-full e-flex e-con e-child\" data-id=\"6f52561\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d0029fb elementor-widget elementor-widget-image\" data-id=\"d0029fb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/pulito.png\" class=\"attachment-large size-large wp-image-1646\" alt=\"Logo Super Pulito\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/pulito.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/pulito-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3a5c8e elementor-widget elementor-widget-image\" data-id=\"a3a5c8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/haugweiser.png\" class=\"attachment-large size-large wp-image-1644\" alt=\"Logo Haug-Weiser\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/haugweiser.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/haugweiser-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca6153d elementor-widget elementor-widget-image\" data-id=\"ca6153d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/containerdienst.png\" class=\"attachment-large size-large wp-image-1641\" alt=\"Logo Containerdienst Birkenfeld\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/containerdienst.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/containerdienst-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-987189a e-con-full e-flex e-con e-child\" data-id=\"987189a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-033da60 elementor-widget elementor-widget-image\" data-id=\"033da60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/Kantwerg.png\" class=\"attachment-large size-large wp-image-1645\" alt=\"Logo Kantwerg\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/Kantwerg.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/Kantwerg-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6219311 elementor-widget elementor-widget-image\" data-id=\"6219311\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/gwinner.png\" class=\"attachment-large size-large wp-image-1643\" alt=\"Logo Gwinner\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/gwinner.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/gwinner-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-970d72c elementor-widget elementor-widget-image\" data-id=\"970d72c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"130\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/dunkelberg.png\" class=\"attachment-large size-large wp-image-1642\" alt=\"Logo Systemhaus Dunkelberg\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/dunkelberg.png 350w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/dunkelberg-300x111.png 300w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d8b1db e-flex e-con-boxed e-con e-parent\" data-id=\"9d8b1db\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8bb245f e-con-full e-flex e-con e-child\" data-id=\"8bb245f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3ac5c elementor-widget elementor-widget-image\" data-id=\"fc3ac5c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"304\" height=\"222\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/auto.png\" class=\"attachment-large size-large wp-image-1640\" alt=\"Bild vom Werbefahrzeug\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/auto.png 304w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/auto-300x219.png 300w\" sizes=\"(max-width: 304px) 100vw, 304px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e93329 e-con-full e-flex e-con e-child\" data-id=\"5e93329\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5fc099 e-flex e-con-boxed e-con e-parent\" data-id=\"c5fc099\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cf54e91 e-con-full e-flex e-con e-child\" data-id=\"cf54e91\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6f3a71 elementor-widget elementor-widget-heading\" data-id=\"b6f3a71\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ehrenamtliche Arbeit\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff722a5 e-con-full e-flex e-con e-child\" data-id=\"ff722a5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57169d6 elementor-widget elementor-widget-text-editor\" data-id=\"57169d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"pclass\" align=\"justify\">Die ehrenamtliche Arbeit spielt in unserer Einrichtung eine wichtige Rolle. Die Mitglieder des Verwaltungsrates tragen mit zur Entwicklung der August-Kayser-Stiftung bei und bringen Impulse mit in die Einrichtung.<br \/><br \/>Engagierte Ehrenamtliche bringen sich in das Leben der August-Kayser-Stiftung mit ein und machen das Haus dadurch ein St\u00fcck lebenswerter. Allen, die einen Teil ihrer Freizeit f\u00fcr die August-Kayser-Stiftung aufbringen gilt unser besonderer Dank.<br \/><br \/>Arbeiten auch Sie ehrenamtlich mit im Team der August-Kayser-Stiftung.<\/div><div class=\"pclass\" align=\"justify\">Frau Elisabeth Komorek freut sich \u00fcber Ihren Anruf (Tel. 07231-9660-10) und ber\u00e4t Sie gern \u00fcber die vielf\u00e4ltigen M\u00f6glichkeiten ehrenamtlicher T\u00e4tigkeiten im Pflegeheim.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27d7d2d elementor-widget elementor-widget-button\" data-id=\"27d7d2d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/konzept-ehrenamt-04-10.zip\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download Konzept Ehrenamt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e32234a e-con-full e-flex e-con e-child\" data-id=\"e32234a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8705347 elementor-widget elementor-widget-image\" data-id=\"8705347\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050242-1024x683.jpg\" class=\"attachment-large size-large wp-image-1479\" alt=\"Eingangsstele der August-Kayser-Stiftung\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050242-1024x683.jpg 1024w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/09\/20240715_erlenmayerdigital_aks_L1050242-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea3bd6b e-flex e-con-boxed e-con e-parent\" data-id=\"ea3bd6b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52d1407 elementor-widget elementor-widget-heading\" data-id=\"52d1407\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Verwaltungsrat\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5600be elementor-widget elementor-widget-text-editor\" data-id=\"c5600be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Leitung und Verwaltung der Stiftung obliegt dem Verwaltungsrat.<\/p><p>Der Verwaltungsrat besteht aus bis zu 9 Mitgliedern .<\/p><p>Der Vorsitzende ist f\u00fcr die Gesch\u00e4fte der laufenden Verwaltung und f\u00fcr die Erledigung von Aufgaben zust\u00e4ndig, die nicht der Entscheidung des Verwaltungsrates vorbehalten sind.\u00a0<\/p><p>Das Gremium ist ehrenamtlich t\u00e4tig.<\/p><p><strong>Mitglieder des Verwaltungsrates:<\/strong><\/p><p>1. Vorsitzender: Ulli Wetzel<br \/>Stellv. Vorsitzender: Hendrik Digel<br \/>Stellv. Vorsitzender: Bastian Meyer<br \/>Sven K\u00f6feler<br \/>Carsten von Zeppelin<br \/>Dr. Stefanie Weis <br \/>PD Dr. rer. nat. Afsaneh Soruri<\/p><p><strong>Ansprechpartner<\/strong><\/p><p>August-Kayser-Stiftung<br \/>Heimleitung: Brigitte Klitta<br \/>August-Kayser-Stra\u00dfe 23<br \/>75175 Pforzheim<\/p><p>Tel. 07231 \/ 9660-56<br \/>Fax 07231 \/ 9660-14<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-302f34b e-flex e-con-boxed e-con e-parent\" data-id=\"302f34b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-524b6da e-con-full e-flex e-con e-child\" data-id=\"524b6da\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0696614 elementor-widget elementor-widget-heading\" data-id=\"0696614\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Geschichte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3eb63 elementor-widget elementor-widget-text-editor\" data-id=\"4c3eb63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 data-sourcepos=\"3:1-3:46\"><strong>August Kayser \u2013 Ein Leben f\u00fcr Pforzheim<\/strong><\/h2><p data-sourcepos=\"5:1-5:32\"><strong>Der Gr\u00fcnder unserer Stiftung<\/strong><\/p><p data-sourcepos=\"7:1-7:227\">August Kayser, geboren am 14. Februar 1834 in Pforzheim, war mehr als nur ein erfolgreicher Privatbankier und Politiker. Sein Leben war gepr\u00e4gt von einem tiefen sozialen Engagement und einer gro\u00dfen Liebe zu seiner Heimatstadt.<\/p><p data-sourcepos=\"9:1-9:40\"><strong>Von Pforzheim in die Welt und zur\u00fcck<\/strong><\/p><p data-sourcepos=\"11:1-11:364\">Nach seiner Schulzeit in Pforzheim, Genf und Paris, absolvierte Kayser eine kaufm\u00e4nnische Ausbildung in Karlsruhe und Leipzig. Seine Sprachstudien f\u00fchrten ihn nach England. Zur\u00fcck in Pforzheim, entwickelte er sich zu einer einflussreichen Pers\u00f6nlichkeit. Als Stadtrat und Vorsitzender der Stadtverordneten pr\u00e4gte er die politische Landschaft Pforzheims ma\u00dfgeblich.<\/p><p data-sourcepos=\"13:1-13:32\"><strong>Ein Herz f\u00fcr die Schw\u00e4chsten<\/strong><\/p><p data-sourcepos=\"15:1-15:323\">Trotz seines gro\u00dfen Reichtums lebte Kayser zur\u00fcckgezogen und bescheiden. Sein Hauptaugenmerk galt stets dem Wohl seiner Mitb\u00fcrger. Nach z\u00e4hen Verhandlungen mit der Stadtverwaltung erwarb er die Wasserrechte am unteren Hammer, deren Erl\u00f6se er vollst\u00e4ndig in den Bau eines &#8222;Altersheims f\u00fcr Invaliden der Arbeit&#8220; investierte.<\/p><p data-sourcepos=\"27:1-27:81\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1551322 elementor-widget elementor-widget-image\" data-id=\"1551322\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"176\" height=\"212\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/10\/august-kayser.jpg\" class=\"attachment-large size-large wp-image-1658\" alt=\"Altes Portrait von August Kayser\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec3c7b1 e-con-full e-flex e-con e-child\" data-id=\"ec3c7b1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c21c72f elementor-widget elementor-widget-spacer\" data-id=\"c21c72f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef9bf0f elementor-widget elementor-widget-text-editor\" data-id=\"ef9bf0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"17:1-17:29\"><strong>Unvergessen und gew\u00fcrdigt<\/strong><\/p><p data-sourcepos=\"19:1-19:288\">Am 29. Dezember 1905 wurde die Stiftungs-Urkunde der August-Kayser-Stiftung verfasst. 1911 er\u00f6ffnete das Altersheim, das bis heute als ein Ort der Pflege und F\u00fcrsorge f\u00fcr \u00e4ltere Menschen dient. August Kayser starb am 18. Juni 1914, sein Verm\u00e4chtnis lebt jedoch in unserer Stiftung weiter.<\/p><p data-sourcepos=\"21:1-21:47\"><strong>Sein Lebenswerk: Die August-Kayser-Stiftung<\/strong><\/p><p data-sourcepos=\"23:1-23:384\">Die August-Kayser-Stiftung ist ein Ausdruck von August Kaysers unerm\u00fcdlichem Einsatz f\u00fcr seine Mitmenschen. Sein Wunsch, ein Zuhause f\u00fcr bed\u00fcrftige Menschen zu schaffen, hat bis heute Bestand. Als moderne Dienstleisterin f\u00fcr Seniorinnen und Senioren setzen wir uns daf\u00fcr ein, dass die Bewohnerinnen und Bewohner unseres Hauses ein selbstbestimmtes und w\u00fcrdevolles Leben f\u00fchren k\u00f6nnen.<\/p><p data-sourcepos=\"25:1-25:68\"><strong>M\u00f6chten Sie mehr \u00fcber August Kayser und seine Stiftung erfahren?<\/strong><\/p><p data-sourcepos=\"27:1-27:81\">Besuchen Sie uns gerne vor Ort oder kontaktieren Sie uns. Wir freuen uns auf Sie!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd3dced elementor-widget elementor-widget-image\" data-id=\"bd3dced\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"371\" src=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/06\/hausordnung.jpg\" class=\"attachment-large size-large wp-image-1338\" alt=\"Bild der alten Hausordnung\" srcset=\"https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/06\/hausordnung.jpg 500w, https:\/\/august-kayser-stiftung.de\/wp-content\/uploads\/2024\/06\/hausordnung-300x223.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56fbc5d e-con-full e-flex e-con e-child\" data-id=\"56fbc5d\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7146ab e-con-full e-flex e-con e-child\" data-id=\"e7146ab\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ansprechpartner Heimleitung: Brigitte Klitta Dimitri Eberle(Pflegedienstleiter) Tel. 07231\/96 60 50Fax 07231\/96 60 14\u00a0E-Mail:\u00a0dimitri.eberle@august-kayser-stiftung.de\u00a0Elisabeth Komorek(Leiterin des Sozialdienstes) Tel. 07231\/96 60 10Fax 07231\/96 60 14\u00a0E-Mail:\u00a0elisabeth.komorek@august-kayser-stiftung.de Unsere Sponsoren Die August Kayser Stiftung bedankt sich recht herzlich f\u00fcr die Unterst\u00fctzung! Ehrenamtliche Arbeit Die ehrenamtliche Arbeit spielt in unserer Einrichtung eine wichtige Rolle. Die Mitglieder des Verwaltungsrates tragen mit zur [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"ocean_post_layout":"full-width","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","footnotes":""},"class_list":["post-465","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/pages\/465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/comments?post=465"}],"version-history":[{"count":103,"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/pages\/465\/revisions"}],"predecessor-version":[{"id":1935,"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/pages\/465\/revisions\/1935"}],"wp:attachment":[{"href":"https:\/\/august-kayser-stiftung.de\/index.php\/wp-json\/wp\/v2\/media?parent=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}